{"id":659,"date":"2023-01-25T16:57:15","date_gmt":"2023-01-25T15:57:15","guid":{"rendered":"https:\/\/marecettedubonheur.com\/?p=659"},"modified":"2026-08-18T19:04:01","modified_gmt":"2026-08-18T17:04:01","slug":"identite-et-identification","status":"publish","type":"post","link":"https:\/\/marecettedubonheur.com\/index.php\/2023\/01\/25\/identite-et-identification\/","title":{"rendered":"Identit\u00e9 et identification"},"content":{"rendered":"\n<p>Comme beaucoup de gens je suppose, je me pose depuis longtemps la question : \u00ab&nbsp;qui suis-je&nbsp;?&nbsp;\u00bb. J\u2019ai cherch\u00e9 dans des livres, des enseignements de grands ma\u00eetres, des th\u00e9ories de grands penseurs, des romans, des pratiques, des t\u00e9moignages\u2026 m\u2019identifiant \u00e0 tout ce que je d\u00e9couvrais de moi. Mais, <em>en vrai<\/em>, sont-ce des r\u00e9ponses&nbsp;?<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Pendant la p\u00e9riode des Nuits Saintes 2022, \u00e0 40 ans, j\u2019ai eu une r\u00e9v\u00e9lation. Enfin, c\u2019est une r\u00e9v\u00e9lation pour moi, un changement de ma fa\u00e7on de penser. Ce n\u2019est s\u00fbrement pas une r\u00e9v\u00e9lation pour tout le monde&nbsp;! Et c\u2019est ce parcours que j\u2019ai eu, ces recherches que j\u2019ai faites, ces rencontres qui m\u2019ont aid\u00e9e \u00e0 me transformer, cette qu\u00eate d\u2019identit\u00e9 que j\u2019ai poursuivie, qui m\u2019ont men\u00e9e \u00e0 cette \u00ab&nbsp;conclusion&nbsp;\u00bb <a href=\"#lectures\"><b>[1]<\/b><\/a>. Je la mets entre guillemets, car l\u2019exp\u00e9rience m\u2019a montr\u00e9 que les conclusions finales n\u2019existent pas&nbsp;! C\u2019est ma conclusion du moment \ud83d\ude09<\/p>\n\n\n\n<p>Et comme beaucoup de \u00ab&nbsp;r\u00e9v\u00e9lations&nbsp;\u00bb, je le savais d\u00e9j\u00e0, intellectuellement, inconsciemment. C\u2019est quelque chose que j\u2019ai lu, entendu plein de fois. Que de grands sages ont dit, ont enseign\u00e9. Mais c\u2019est la premi\u00e8re fois que je le vis. Que je l\u2019exp\u00e9rimente. Que je le comprends (<em>prends avec<\/em>), du moins selon mon niveau actuel. <\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>C&rsquo;est la premi\u00e8re fois que mon c\u0153ur me le dit et que je sens cette lumi\u00e8re, cette confiance, ce bien-\u00eatre, ce soulagement, cette \u00e9vidence.<\/p><\/blockquote><\/figure>\n\n\n\n<p>Alors je vous la partage, pour que vous l\u2019entendiez une fois de plus. Pour que, peut-\u00eatre, cette formulation qui n\u2019est pas celle d\u2019un grand ma\u00eetre mais d\u2019une humble qu\u00eateuse qui s\u2019\u00e9merveille de (re)d\u00e9couvrir cela, vous parle. Pour que vous puissiez un jour vous reconna\u00eetre, \u00e0 votre fa\u00e7on, avec vos mots.<\/p>\n\n\n\n<p>Cette v\u00e9rit\u00e9, ma V\u00e9rit\u00e9, je la ressens, mais je ne la vis pas encore pleinement. Elle m\u2019accompagne, m\u2019encourage, me permet de prendre de la hauteur par rapport \u00e0 ce que je vis. Elle ne m\u2019emp\u00eache pas de tomber, mais m\u2019aide \u00e0 ne pas tomber \u00ab&nbsp;trop&nbsp;\u00bb bas. Elle est un fil attach\u00e9 au ciel auquel je peux me raccrocher pour stopper ma chute et remonter.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Je suis<\/h2>\n\n\n\n<p>Je suis un \u00eatre spirituel et vivant<br>Je suis une manifestation de l\u2019Amour divin<br>Je suis une \u00e9tincelle de lumi\u00e8re<br>Je suis un feu de joie<br>Je suis un \u00eatre sacr\u00e9<br>Je suis un \u00eatre cr\u00e9ateur<\/p>\n\n\n\n<p>Je ne suis pas mon corps<br>Je ne suis pas ma personnalit\u00e9<br>Je ne suis pas mes comp\u00e9tences<br>Je ne suis pas mes qualit\u00e9s<br>Rien de tout cela n\u2019est moi.<br>Je suis bien plus que cela.<br>Je suis au-del\u00e0 de cela.<br>Rien de tout cela ne m\u2019appartient<br>Ce sont des outils pour cr\u00e9er ce que Je veux.<\/p>\n\n\n\n<p>Comme tout outil, ils sont rempla\u00e7ables, modelables, transformables, \u00e9volutifs.<br>Ils servent \u00e0 cr\u00e9er l\u2019\u0153uvre, et l\u2019\u0153uvre est plus importante que l\u2019outil.<br>Si je romps ou perds ou qu\u2019on m\u2019enl\u00e8ve un outil, ce n\u2019est pas grave.<br>J\u2019ai confiance dans le fait que je trouverai toujours les ressources dont j\u2019ai besoin pour cr\u00e9er ce que Je veux, que je saurai le \u00ab&nbsp;remplacer&nbsp;\u00bb, le \u00ab&nbsp;r\u00e9parer&nbsp;\u00bb, faire sans, ou avec l\u2019outil \u00ab&nbsp;cass\u00e9&nbsp;\u00bb, modifi\u00e9.<br>Je respecte mes outils, mais n\u2019oublie pas ce qu\u2019ils sont. Ne pas utiliser un outil est plus irrespectueux que de l\u2019utiliser et ainsi l\u2019abimer ou le casser. Cela le prive de sa raison d\u2019\u00eatre.<\/p>\n\n\n\n<p>Je ne suis pas mes pens\u00e9es<br>Je ne suis pas mes id\u00e9es<br>Je ne suis pas mes intuitions<br>Je ne suis pas mes inspirations<br>Je ne suis pas mes besoins<br>Je ne suis pas mes envies<br>Je ne suis pas mes d\u00e9sirs<br>Rien de tout cela ne m\u2019appartient.<br>Ils sont des pistes, des outils qui m\u2019aident \u00e0 d\u00e9couvrir ce que Je veux, \u00e0 le discerner.<\/p>\n\n\n\n<p>Je ne suis pas mes d\u00e9fauts<br>Je ne suis pas mes peurs<br>Je ne suis pas mes \u00e9motions<br>Je ne suis pas mes ressentis<br>Je ne suis pas mes sentiments<br>Rien de tout cela ne m\u2019appartient.<br>Ils sont des pistes, des outils qui me montrent ce que je dois transformer, d\u00e9passer, faire \u00e9voluer, pour cr\u00e9er ce que Je veux.<\/p>\n\n\n\n<p>Je ne suis pas mes cr\u00e9ations<br>Je ne suis pas mes actes<br>Je ne suis pas mes exp\u00e9riences<br>Ils sont le fruit de la fa\u00e7on dont j\u2019ai utilis\u00e9 mes outils pour cr\u00e9er ce que Je veux\u2026 ou pas.<\/p>\n\n\n\n<p>Je ne suis pas mes r\u00e9ussites<br>Je ne suis pas mes \u00e9checs<br>Ils me montrent o\u00f9 j\u2019en suis, le chemin parcouru et \u00e0 parcourir pour r\u00e9ussir \u00e0 cr\u00e9er ce que Je veux. Quels outils faire \u00e9voluer, transformer.<\/p>\n\n\n\n<p>Je suis un \u00eatre cr\u00e9ateur<br>\u00c0 l\u2019image du P\u00e8re, du yang<br>J\u2019apprends \u00e0 cr\u00e9er et \u00e0 manifester<br>\u00c0 l\u2019image de la M\u00e8re, du yin<br>Car je suis Yin ET Yang<\/p>\n\n\n\n<p>Je suis un \u00eatre d\u2019Amour<br>Disposant d\u2019outils pour cr\u00e9er sur Terre<br>Ces outils servent \u00e0 cela<br>Ils sont \u00e9ph\u00e9m\u00e8res et moins importants que l\u2019\u0153uvre<br>Ils servent \u00e0 cr\u00e9er<br>Ils servent \u00e0 exp\u00e9rimenter<br>Ils servent \u00e0 v\u00e9hiculer l\u2019Amour.<\/p>\n\n\n\n<p>Alors, je m\u2019en sers,<br>Comme les outils qu\u2019ils sont,<br>J\u2019en prends soin mais ne m\u2019y attache pas<br>Je les respecte en les utilisant pour ce qu\u2019ils sont<br>Et je ne m\u2019y identifie pas<br>Car ils ne sont pas Moi.<\/p>\n\n\n\n<p>Et cela vaut pour tout \u00catre.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"984\" src=\"https:\/\/marecettedubonheur.com\/wp-content\/uploads\/2023\/01\/person-1053543-1024x984.jpg\" alt=\"\" class=\"wp-image-661\" srcset=\"https:\/\/marecettedubonheur.com\/wp-content\/uploads\/2023\/01\/person-1053543-1024x984.jpg 1024w, https:\/\/marecettedubonheur.com\/wp-content\/uploads\/2023\/01\/person-1053543-300x288.jpg 300w, https:\/\/marecettedubonheur.com\/wp-content\/uploads\/2023\/01\/person-1053543-768x738.jpg 768w, https:\/\/marecettedubonheur.com\/wp-content\/uploads\/2023\/01\/person-1053543-1536x1476.jpg 1536w, https:\/\/marecettedubonheur.com\/wp-content\/uploads\/2023\/01\/person-1053543.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"lectures\">Derni\u00e8res lectures qui m&rsquo;ont amen\u00e9es l\u00e0<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>Conversation avec Dieu<\/em> de Neale Donald Walsh<\/li>\n\n\n\n<li><em>La Voie du Tarot<\/em> d&rsquo;Alexandro Jodorowsky &amp; Marianne Costa (tarot de Marseille version connaissance de soi\/spiritualit\u00e9 et non divination)<\/li>\n<\/ul>\n\n\n\n<p>Je ne peux \u00eatre exhaustive quant \u00e0 tout ce que j&rsquo;ai lu, pratiqu\u00e9, exp\u00e9riment\u00e9, pour en arriver \u00e0 cette \u00ab\u00a0r\u00e9v\u00e9lation\u00a0\u00bb pour moi, c&rsquo;est pourquoi je ne vous liste ici que les derniers ouvrages qui l&rsquo;ont fait sortir \u00e0 ma conscience ! <br>Et cela ouvre d&rsquo;autres portes encore, nourries d&rsquo;autres exp\u00e9riences&#8230;<\/p>\n\n\n\n<p>To be continued&#8230; \ud83d\ude09<\/p>\n\n\n\n<p class=\"has-text-align-right\"><small><em>Photos : Une (Femme) : \u00a9Ryan McGuire\/Pixabay &#8211; Jeune fille : \u00a9Petra\/Pixabay<\/em><\/small><\/p>\n<div data-animation=\"rubberBand\" data-icons-animation=\"no-animation\" data-overlay=\"on\" data-change-size=\"\" data-button-size=\"0.7\" style=\"font-size:0.7em!important;display:none;\" class=\"supsystic-social-sharing supsystic-social-sharing-package-flat supsystic-social-sharing-hide-on-homepage supsystic-social-sharing-spacing supsystic-social-sharing-content supsystic-social-sharing-content-align-left\" data-text=\"\"><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-3 counter-standard without-counter facebook\" target=\"_blank\" title=\"Facebook\" href=\"http:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fmarecettedubonheur.com%2Findex.php%2F2023%2F01%2F25%2Fidentite-et-identification%2F\" data-main-href=\"http:\/\/www.facebook.com\/sharer.php?u={url}\" data-nid=\"1\" data-name=\"\" data-pid=\"1\" data-post-id=\"659\" data-url=\"https:\/\/marecettedubonheur.com\/wp-admin\/admin-ajax.php\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-facebook\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">0<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-3 counter-standard without-counter twitter\" target=\"_blank\" title=\"Twitter\" href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fmarecettedubonheur.com%2Findex.php%2F2023%2F01%2F25%2Fidentite-et-identification%2F&text=Identit%C3%A9+et+identification\" data-main-href=\"https:\/\/twitter.com\/share?url={url}&text={title}\" data-nid=\"2\" data-name=\"\" data-pid=\"1\" data-post-id=\"659\" data-url=\"https:\/\/marecettedubonheur.com\/wp-admin\/admin-ajax.php\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-twitter\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">0<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-3 counter-standard like\" target=\"_blank\" title=\"Like\" href=\"#\" data-main-href=\"#\" data-nid=\"5\" data-name=\"\" data-pid=\"1\" data-post-id=\"659\" data-url=\"https:\/\/marecettedubonheur.com\/wp-admin\/admin-ajax.php\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-heart\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">3<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-3 counter-standard without-counter pinterest\" target=\"_blank\" title=\"Partager sur Pinterest\" href=\"http:\/\/pinterest.com\/pin\/create\/link\/?url=https%3A%2F%2Fmarecettedubonheur.com%2Findex.php%2F2023%2F01%2F25%2Fidentite-et-identification%2F&description=Identit%C3%A9+et+identification\" data-main-href=\"http:\/\/pinterest.com\/pin\/create\/link\/?url={url}&description={title}\" data-nid=\"7\" data-name=\"\" data-pid=\"1\" data-post-id=\"659\" data-url=\"https:\/\/marecettedubonheur.com\/wp-admin\/admin-ajax.php\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-pinterest\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">0<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-3 counter-standard without-counter mail\" target=\"_blank\" title=\"Partager par Mail\" href=\"#\" data-main-href=\"#\" data-nid=\"16\" data-name=\"\" data-pid=\"1\" data-post-id=\"659\" data-url=\"https:\/\/marecettedubonheur.com\/wp-admin\/admin-ajax.php\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-envelope-o\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">0<\/span><\/div><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Comme beaucoup de gens je suppose, je me pose depuis longtemps la question : \u00ab&nbsp;qui suis-je&nbsp;?&nbsp;\u00bb. J\u2019ai cherch\u00e9 dans des &hellip; <\/p>\n<div data-animation=\"rubberBand\" data-icons-animation=\"no-animation\" data-overlay=\"on\" data-change-size=\"\" data-button-size=\"0.7\" style=\"font-size:0.7em!important;display:none;\" class=\"supsystic-social-sharing supsystic-social-sharing-package-flat supsystic-social-sharing-hide-on-homepage supsystic-social-sharing-spacing supsystic-social-sharing-content supsystic-social-sharing-content-align-left\" data-text=\"\"><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-3 counter-standard without-counter facebook\" target=\"_blank\" title=\"Facebook\" href=\"http:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fmarecettedubonheur.com%2Findex.php%2F2023%2F01%2F25%2Fidentite-et-identification%2F\" data-main-href=\"http:\/\/www.facebook.com\/sharer.php?u={url}\" data-nid=\"1\" data-name=\"\" data-pid=\"1\" data-post-id=\"659\" data-url=\"https:\/\/marecettedubonheur.com\/wp-admin\/admin-ajax.php\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-facebook\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">0<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-3 counter-standard without-counter twitter\" target=\"_blank\" title=\"Twitter\" href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fmarecettedubonheur.com%2Findex.php%2F2023%2F01%2F25%2Fidentite-et-identification%2F&text=Identit%C3%A9+et+identification\" data-main-href=\"https:\/\/twitter.com\/share?url={url}&text={title}\" data-nid=\"2\" data-name=\"\" data-pid=\"1\" data-post-id=\"659\" data-url=\"https:\/\/marecettedubonheur.com\/wp-admin\/admin-ajax.php\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-twitter\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">0<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-3 counter-standard like\" target=\"_blank\" title=\"Like\" href=\"#\" data-main-href=\"#\" data-nid=\"5\" data-name=\"\" data-pid=\"1\" data-post-id=\"659\" data-url=\"https:\/\/marecettedubonheur.com\/wp-admin\/admin-ajax.php\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-heart\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">3<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-3 counter-standard without-counter pinterest\" target=\"_blank\" title=\"Partager sur Pinterest\" href=\"http:\/\/pinterest.com\/pin\/create\/link\/?url=https%3A%2F%2Fmarecettedubonheur.com%2Findex.php%2F2023%2F01%2F25%2Fidentite-et-identification%2F&description=Identit%C3%A9+et+identification\" data-main-href=\"http:\/\/pinterest.com\/pin\/create\/link\/?url={url}&description={title}\" data-nid=\"7\" data-name=\"\" data-pid=\"1\" data-post-id=\"659\" data-url=\"https:\/\/marecettedubonheur.com\/wp-admin\/admin-ajax.php\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-pinterest\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">0<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-3 counter-standard without-counter mail\" target=\"_blank\" title=\"Partager par Mail\" href=\"#\" data-main-href=\"#\" data-nid=\"16\" data-name=\"\" data-pid=\"1\" data-post-id=\"659\" data-url=\"https:\/\/marecettedubonheur.com\/wp-admin\/admin-ajax.php\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-envelope-o\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">0<\/span><\/div><\/a><\/div>","protected":false},"author":1,"featured_media":664,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[50,67,35,34],"class_list":["post-659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reflexions","tag-amour","tag-identite","tag-liberte","tag-spiritualite"],"_links":{"self":[{"href":"https:\/\/marecettedubonheur.com\/index.php\/wp-json\/wp\/v2\/posts\/659"}],"collection":[{"href":"https:\/\/marecettedubonheur.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marecettedubonheur.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marecettedubonheur.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marecettedubonheur.com\/index.php\/wp-json\/wp\/v2\/comments?post=659"}],"version-history":[{"count":12,"href":"https:\/\/marecettedubonheur.com\/index.php\/wp-json\/wp\/v2\/posts\/659\/revisions"}],"predecessor-version":[{"id":739,"href":"https:\/\/marecettedubonheur.com\/index.php\/wp-json\/wp\/v2\/posts\/659\/revisions\/739"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marecettedubonheur.com\/index.php\/wp-json\/wp\/v2\/media\/664"}],"wp:attachment":[{"href":"https:\/\/marecettedubonheur.com\/index.php\/wp-json\/wp\/v2\/media?parent=659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marecettedubonheur.com\/index.php\/wp-json\/wp\/v2\/categories?post=659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marecettedubonheur.com\/index.php\/wp-json\/wp\/v2\/tags?post=659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}